{"id":3,"date":"2024-10-14T10:43:24","date_gmt":"2024-10-14T10:43:24","guid":{"rendered":"https:\/\/alargascencia.org\/?page_id=3"},"modified":"2025-11-25T08:54:01","modified_gmt":"2025-11-25T07:54:01","slug":"politica-de-privacidad","status":"publish","type":"page","link":"https:\/\/alargascencia.org\/es\/politica-de-privacidad\/","title":{"rendered":"Pol\u00edtica de Privacidad"},"content":{"rendered":"<p><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container has-pattern-background has-mask-background hundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-top:25px;--awb-padding-bottom:25px;--awb-margin-top:0px;--awb-margin-bottom:80px;--awb-background-color:var(--awb-color8);--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"width:104% !important;max-width:104% !important;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion-flex-column ancho50\" style=\"--awb-bg-size:cover;--awb-width-large:18%;--awb-margin-top-large:0px;--awb-spacing-right-large:10.666666666667%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:10.666666666667%;--awb-width-medium:50%;--awb-order-medium:0;--awb-spacing-right-medium:3.84%;--awb-spacing-left-medium:3.84%;--awb-width-small:50%;--awb-order-small:0;--awb-spacing-right-small:3.84%;--awb-spacing-left-small:0%;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-center fusion-content-layout-column\"><div class=\"fusion-image-element \" style=\"text-align:center;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-1 hover-type-none\"><a class=\"fusion-no-lightbox\" href=\"http:\/\/www.tierra.org\/\" target=\"_blank\" aria-label=\"logo_amigas_de_la_tierra_blanco\" rel=\"noopener noreferrer\"><img decoding=\"async\" width=\"306\" height=\"119\" alt=\"Ir a Amigos de la Tierra\" src=\"https:\/\/alargascencia.org\/wp-content\/uploads\/2025\/11\/logo_amigas_de_la_tierra_blanco.png\" data-orig-src=\"https:\/\/alargascencia.org\/wp-content\/uploads\/2025\/11\/logo_amigas_de_la_tierra_blanco.png\" class=\"lazyload img-responsive wp-image-16231\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27306%27%20height%3D%27119%27%20viewBox%3D%270%200%20306%20119%27%3E%3Crect%20width%3D%27306%27%20height%3D%27119%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/alargascencia.org\/wp-content\/uploads\/2025\/11\/logo_amigas_de_la_tierra_blanco-200x78.png 200w, https:\/\/alargascencia.org\/wp-content\/uploads\/2025\/11\/logo_amigas_de_la_tierra_blanco.png 306w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 1024px) 100vw, (max-width: 640px) 100vw, 306px\" \/><\/a><\/span><\/div><\/div><\/div>\n<div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion-flex-column fusion-flex-align-self-flex-start ancho50\" style=\"--awb-bg-size:cover;--awb-width-large:64%;--awb-margin-top-large:25px;--awb-spacing-right-large:3%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:3%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:50%;--awb-order-small:0;--awb-spacing-right-small:3.84%;--awb-spacing-left-small:0%;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><nav class=\"awb-menu awb-menu_row awb-menu_em-hover mobile-mode-collapse-to-button awb-menu_icons-left awb-menu_dc-yes mobile-trigger-fullwidth-off awb-menu_mobile-toggle awb-menu_indent-left mobile-size-full-absolute loading mega-menu-loading awb-menu_desktop awb-menu_dropdown awb-menu_expand-right awb-menu_transition-fade negrita \" style=\"--awb-font-size:14px;--awb-text-transform:uppercase;--awb-justify-content:flex-end;--awb-items-padding-right:5px;--awb-items-padding-left:5px;--awb-color:var(--awb-color1);--awb-active-color:#ffffff;--awb-active-border-color:var(--awb-color1);--awb-submenu-text-transform:none;--awb-icons-size:21;--awb-icons-color:hsla(var(--awb-color8-h),var(--awb-color8-s),calc( var(--awb-color8-l) + 16% ),var(--awb-color8-a));--awb-main-justify-content:flex-start;--awb-mobile-nav-button-align-hor:flex-end;--awb-mobile-bg:hsla(var(--awb-color8-h),var(--awb-color8-s),calc( var(--awb-color8-l) + 97% ),var(--awb-color8-a));--awb-mobile-color:var(--awb-color7);--awb-mobile-active-bg:var(--awb-color1);--awb-mobile-active-color:var(--awb-color4);--awb-mobile-trigger-font-size:20px;--awb-trigger-padding-right:0px;--awb-mobile-trigger-color:var(--awb-color1);--awb-mobile-trigger-background-color:rgba(255,255,255,0);--awb-mobile-nav-trigger-bottom-margin:28px;--awb-justify-title:flex-start;--awb-mobile-justify:flex-start;--awb-mobile-caret-left:auto;--awb-mobile-caret-right:0;--awb-box-shadow:0px -4px 0px 0px var(--awb-color4);;--awb-fusion-font-family-typography:inherit;--awb-fusion-font-style-typography:normal;--awb-fusion-font-weight-typography:400;--awb-fusion-font-family-submenu-typography:&quot;OKIKU&quot;;--awb-fusion-font-style-submenu-typography:normal;--awb-fusion-font-weight-submenu-typography:400;--awb-fusion-font-family-mobile-typography:inherit;--awb-fusion-font-style-mobile-typography:normal;--awb-fusion-font-weight-mobile-typography:400;\" aria-label=\"Men\u00fa principal\" data-breakpoint=\"1080\" data-count=\"0\" data-transition-type=\"fade\" data-transition-time=\"300\" data-expand=\"right\"><button type=\"button\" class=\"awb-menu__m-toggle awb-menu__m-toggle_no-text\" aria-expanded=\"false\" aria-controls=\"menu-menu-principal\"><span class=\"awb-menu__m-toggle-inner\"><span class=\"collapsed-nav-text\"><span class=\"screen-reader-text\">Toggle Navigation<\/span><\/span><span class=\"awb-menu__m-collapse-icon awb-menu__m-collapse-icon_no-text\"><span class=\"awb-menu__m-collapse-icon-open awb-menu__m-collapse-icon-open_no-text classic-bars-solid\"><\/span><span class=\"awb-menu__m-collapse-icon-close awb-menu__m-collapse-icon-close_no-text classic-times-solid\"><\/span><\/span><\/span><\/button><ul id=\"menu-menu-principal\" class=\"fusion-menu awb-menu__main-ul awb-menu__main-ul_row\"><li  id=\"menu-item-16485\"  class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-16485 awb-menu__li awb-menu__main-li awb-menu__main-li_regular\"  data-item-id=\"16485\"><span class=\"awb-menu__main-background-default awb-menu__main-background-default_fade\"><\/span><span class=\"awb-menu__main-background-active awb-menu__main-background-active_fade\"><\/span><a  href=\"\/\" class=\"awb-menu__main-a awb-menu__main-a_regular\"><span class=\"menu-text\">Inicio<\/span><\/a><\/li><li  id=\"menu-item-5263\"  class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-5263 awb-menu__li awb-menu__main-li awb-menu__main-li_regular\"  data-item-id=\"5263\"><span class=\"awb-menu__main-background-default awb-menu__main-background-default_fade\"><\/span><span class=\"awb-menu__main-background-active awb-menu__main-background-active_fade\"><\/span><a  href=\"https:\/\/alargascencia.org\/es\/que-es-alargascencia\/\" class=\"awb-menu__main-a awb-menu__main-a_regular\"><span class=\"menu-text\">\u00bfQu\u00e9 es Alargascencia?<\/span><\/a><\/li><li  id=\"menu-item-5274\"  class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-5274 awb-menu__li awb-menu__main-li awb-menu__main-li_regular\"  data-item-id=\"5274\"><span class=\"awb-menu__main-background-default awb-menu__main-background-default_fade\"><\/span><span class=\"awb-menu__main-background-active awb-menu__main-background-active_fade\"><\/span><a  href=\"https:\/\/alargascencia.org\/es\/establecimientos\/\" class=\"awb-menu__main-a awb-menu__main-a_regular\"><span class=\"menu-text\">Establecimientos<\/span><\/a><\/li><li  id=\"menu-item-16486\"  class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-16486 awb-menu__li awb-menu__main-li awb-menu__main-li_regular\"  data-item-id=\"16486\"><span class=\"awb-menu__main-background-default awb-menu__main-background-default_fade\"><\/span><span class=\"awb-menu__main-background-active awb-menu__main-background-active_fade\"><\/span><a  href=\"https:\/\/alargascencia.org\/es\/derecho-a-reparar\/\" class=\"awb-menu__main-a awb-menu__main-a_regular\"><span class=\"menu-text\">Derecho a reparar<\/span><\/a><\/li><li  id=\"menu-item-5272\"  class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-5272 awb-menu__li awb-menu__main-li awb-menu__main-li_regular\"  data-item-id=\"5272\"><span class=\"awb-menu__main-background-default awb-menu__main-background-default_fade\"><\/span><span class=\"awb-menu__main-background-active awb-menu__main-background-active_fade\"><\/span><a  href=\"https:\/\/alargascencia.org\/es\/contacto\/\" class=\"awb-menu__main-a awb-menu__main-a_regular\"><span class=\"menu-text\">Contacto<\/span><\/a><\/li><\/ul><\/nav><\/div><\/div>\n<div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-2 fusion-flex-column fusion-flex-align-self-flex-start ancho100\" style=\"--awb-bg-size:cover;--awb-width-large:18%;--awb-margin-top-large:35px;--awb-spacing-right-large:10.666666666667%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:10.666666666667%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:0%;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-social-links fusion-social-links-1\" style=\"--awb-margin-top:8px;--awb-margin-right:0px;--awb-margin-bottom:0px;--awb-margin-left:0px;--awb-alignment:center;--awb-box-border-top:0px;--awb-box-border-right:0px;--awb-box-border-bottom:0px;--awb-box-border-left:0px;--awb-icon-colors-hover:var(--awb-color1);--awb-box-colors-hover:var(--awb-custom_color_5);--awb-box-border-color:var(--awb-color8);--awb-box-border-color-hover:var(--awb-color4);\"><div class=\"fusion-social-networks boxed-icons color-type-custom\"><div class=\"fusion-social-networks-wrapper\"><a class=\"fusion-social-network-icon fusion-tooltip fusion-Bluesky awb-icon-Bluesky\" style=\"color:var(--awb-color1);font-size:16px;width:16px;background-color:var(--awb-color8);border-color:var(--awb-color8);border-radius:50%;\" data-placement=\"left\" data-title=\"Bluesky\" data-toggle=\"tooltip\" title=\"Bluesky\" aria-label=\"Bluesky\" target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/bsky.app\/profile\/amigasdelatierra.bsky.social\"><img class=\"lazyload\" decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2720%27%20height%3D%2718%27%20viewBox%3D%270%200%2020%2018%27%3E%3Crect%20width%3D%2720%27%20height%3D%2718%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/alargascencia.org\/wp-content\/uploads\/2024\/10\/blue_b.png\" alt=\"Bluesky\" width=\"20\" height=\"18\" \/><\/a><a class=\"fusion-social-network-icon fusion-tooltip fusion-facebook awb-icon-facebook\" style=\"color:var(--awb-color1);font-size:16px;width:16px;background-color:var(--awb-color8);border-color:var(--awb-color8);border-radius:50%;\" data-placement=\"left\" data-title=\"Facebook\" data-toggle=\"tooltip\" title=\"Facebook\" aria-label=\"facebook\" target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/www.facebook.com\/AmigasdelaTierraEsp\"><\/a><a class=\"fusion-social-network-icon fusion-tooltip fusion-instagram awb-icon-instagram\" style=\"color:var(--awb-color1);font-size:16px;width:16px;background-color:var(--awb-color8);border-color:var(--awb-color8);border-radius:50%;\" data-placement=\"left\" data-title=\"Instagram\" data-toggle=\"tooltip\" title=\"Instagram\" aria-label=\"instagram\" target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/www.instagram.com\/amigasdelatierra_esp\/\"><\/a><a class=\"fusion-social-network-icon fusion-tooltip fusion-youtube awb-icon-youtube\" style=\"color:var(--awb-color1);font-size:16px;width:16px;background-color:var(--awb-color8);border-color:var(--awb-color8);border-radius:50%;\" data-placement=\"left\" data-title=\"YouTube\" data-toggle=\"tooltip\" title=\"YouTube\" aria-label=\"youtube\" target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/www.youtube.com\/user\/AmigosdelaTierra\"><\/a><\/div><\/div><\/div><\/div><\/div>\n<\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-2 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling z-index-oculta\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-margin-top:-15px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1424.8px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-3 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-title title fusion-title-1 fusion-title-text fusion-title-size-one\" style=\"--awb-margin-top-small:0px;--awb-margin-bottom-small:20px;\"><div class=\"title-sep-container title-sep-container-left fusion-no-large-visibility fusion-no-medium-visibility fusion-no-small-visibility\"><div class=\"title-sep sep- sep-solid\" style=\"border-color:var(--awb-color3);\"><\/div><\/div><span class=\"awb-title-spacer fusion-no-large-visibility fusion-no-medium-visibility fusion-no-small-visibility\"><\/span><h1 class=\"fusion-title-heading title-heading-left fusion-responsive-typography-calculated\" style=\"margin:0;text-transform:capitalize;--fontSize:60;line-height:var(--awb-typography1-line-height);\">Pol\u00edtica de privacidad<\/h1><span class=\"awb-title-spacer\"><\/span><div class=\"title-sep-container title-sep-container-right\"><div class=\"title-sep sep- sep-solid\" style=\"border-color:var(--awb-color3);\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-3 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling z-index-oculta\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-margin-top:-10px;--awb-margin-bottom:30px;--awb-background-color:var(--awb-color3);--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1424.8px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-4 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-padding-top:30px;--awb-padding-right:30px;--awb-padding-left:30px;--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\"><p><strong>Este sitio web es propiedad de Amigas de la Tierra Espa\u00f1a, una asociaci\u00f3n ecologista espa\u00f1ola con la misi\u00f3n de fomentar el cambio local y global hacia una sociedad respetuosa con el medio ambiente, justa y solidaria, en el marco de la federaci\u00f3n de Amigas de la Tierra Internacional.<\/strong><\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-4 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1424.8px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-5 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-2\"><p><strong>Responsable del fichero del tratamiento de datos personales<\/strong><\/p>\n<p>Amigas de la Tierra con domicilio en Calle Bustos, 2, 28038, Madrid, es el Responsable del tratamiento de los datos personales del Interesado y le informa que estos datos ser\u00e1n tratados de conformidad con lo dispuesto en las normativas vigentes en protecci\u00f3n de datos personales, el Reglamento (UE) 2016\/679 de 27 de abril de 2016 (GDPR), la Ley Org\u00e1nica (ES) 15\/1999 de 13 de diciembre (LOPD) y el Real Decreto (ES) 1720\/2007 de 21 de diciembre (RDLOPD)<\/p>\n<p><strong>Forma de obtenci\u00f3n de sus datos<\/strong><\/p>\n<p>Hemos obtenido sus datos a trav\u00e9s de acciones realizadas en el pasado con Amigas de la Tierra, o con motivo de las relaciones que mantiene en la actualidad con nuestra entidad, bien por su condici\u00f3n de socio\/a, por haber sido donante, haber participado en alguna de nuestras campa\u00f1as, darse de alta como establecimiento colaborador o sugerirlo ser o haber sido voluntario\/a, o bien por haber solicitado informaci\u00f3n sobre nuestras actividades, campa\u00f1as e iniciativas.<\/p>\n<p><strong>Datos personales que tratamos<\/strong><\/p>\n<p>Tratamos los siguientes datos para las finalidades que se explican m\u00e1s adelante:<\/p>\n<p>Datos necesarios para mantener la relaci\u00f3n con socios\/as, donantes, voluntarios\/as, colaboradores y suscriptores de campa\u00f1as y bolet\u00edn, participantes en eventos y acciones de Amigas de la Tierra.<\/p>\n<ul>\n<li>Nombre<\/li>\n<li>Apellidos<\/li>\n<li>DNI<\/li>\n<li>Direcci\u00f3n de correo electr\u00f3nico<\/li>\n<li>N\u00famero de tel\u00e9fono<\/li>\n<\/ul>\n<p>En los casos en los que sea necesario por la naturaleza de la acci\u00f3n y\/o relaci\u00f3n con socios\/as, donantes, voluntarios\/as, colaboradores y suscriptores de campa\u00f1as y bolet\u00edn, podemos llegar a tratar otros datos que se faciliten voluntariamente:<\/p>\n<ul>\n<li>Fecha de nacimiento<\/li>\n<li>Sexo<\/li>\n<li>Idioma de preferencia<\/li>\n<li>Direcci\u00f3n Postal<\/li>\n<li>Aportaci\u00f3n econ\u00f3mica<\/li>\n<li>Datos bancarios<\/li>\n<li>Profesi\u00f3n<\/li>\n<li>Informaci\u00f3n para el ejercicio del voluntariado.<\/li>\n<\/ul>\n<p>Tambi\u00e9n, trataremos aquellos datos adicionales que voluntariamente se faciliten durante las futuras relaciones e interacciones mantenidas con Amigas de la Tierra, incluidos los aportados mediante una red social u otra aplicaci\u00f3n. Estos datos dependen de la propia configuraci\u00f3n de privacidad cada uno tenga, uso de la red social o aplicaci\u00f3n, as\u00ed como de las pol\u00edticas de privacidad propias de cada red social o aplicaci\u00f3n, por lo que recomendamos leer las mismas para conocer las pol\u00edticas de cada red social o aplicaci\u00f3n<strong>.<\/strong><\/p>\n<p><strong>\u00a0Finalidad del tratamiento de datos personales<\/strong><\/p>\n<p>En cumplimiento de lo dispuesto en el Reglamento General de Protecci\u00f3n de Datos, as\u00ed como en cualquier ley nacional que resulte de aplicaci\u00f3n, tratamos los datos personales para cumplir con nuestros objetivos fundacionales: fomentar un cambio local y global hacia una sociedad respetuosa con el medio ambiente, justa y solidaria.\u00a0 Trataremos los datos de nuestros socios\/as, donantes, activistas y simpatizantes para las siguientes finalidades:<\/p>\n<p>Enviar informaci\u00f3n sobre Amigas de la Tierra v\u00eda SMS, tel\u00e9fono, correo postal, e-mail, incluso cuando nuestra relaci\u00f3n haya terminado, salvo que el interesado\/a manifieste lo contrario; y dar respuesta a las peticiones de informaci\u00f3n solicitadas.<br \/>\nPromover la colaboraci\u00f3n econ\u00f3mica con Amigas de la Tierra as\u00ed como otros tipos de participaci\u00f3n activa (firmar campa\u00f1as, etc)<br \/>\nFomentar la colaboraci\u00f3n en Amigas de la Tierra a trav\u00e9s de la red de activistas.<br \/>\nInvitar a actos o eventos que organice Amigas de la Tierra.<\/p>\n<p>Tambi\u00e9n trataremos datos para el env\u00edo, incluso por medios electr\u00f3nicos, de comunicaciones promocionales sobre actividades, campa\u00f1as e iniciativas de naturaleza similar a las que se hayan participado con anterioridad.<\/p>\n<p>El interesado\/a puede oponerse a recibir este tipo de comunicaciones promocionales, ahora o en cualquier otro momento, enviando un correo electr\u00f3nico a\u00a0<a href=\"mailto:sensibilizacion@tierra.org\">sensibilizacion@tierra.org<\/a> o dirigiendo una solicitud a la direcci\u00f3n postal de Amigas de la Tierra.<\/p>\n<p>El tratamiento de datos personales relacionado con el mantenimiento de la relaci\u00f3n con Amigas de la Tierra como socio\/a, donante, voluntario\/a, colaborador\/a o suscriptor\/a, est\u00e1 legitimado al resultar necesario para dar cumplimiento a las obligaciones contractuales derivadas de dicha relaci\u00f3n.<\/p>\n<p>El tratamiento de sus datos personales para el env\u00edo de informaci\u00f3n promocional sobre actividades, campa\u00f1as o iniciativas de Amigas de la Tierra similares a las que se haya participado con anterioridad, responde a un inter\u00e9s leg\u00edtimo de nuestra entidad y est\u00e1 autorizado por la normativa vigente.<\/p>\n<p>El tratamiento de datos personales para el ejercicio del activista es necesario ya que lo establece la normativa vigente sobre el voluntariado.<\/p>\n<p><strong>Legitimaci\u00f3n<\/strong><\/p>\n<p>La base leg\u00edtima para el tratamiento de tus datos es la ejecuci\u00f3n de un contrato con Amigas de la Tierra en relaci\u00f3n con el alta que nos has solicitado.<\/p>\n<p>Asimismo, la base legal del tratamiento de tus datos personales puede darse tambi\u00e9n por el consentimiento expreso que otorgues para cada finalidad en el momento de recogida de tus datos personales que nos proporciones a trav\u00e9s de una posible alta presencial en nuestra sede o stands.<\/p>\n<p><strong>Datos personales y terceros<\/strong><\/p>\n<p>NO venderemos, alquilaremos o cederemos sus datos personales, pero estos podr\u00e1n ser facilitados a los destinatarios que se indican a continuaci\u00f3n, por los motivos que a continuaci\u00f3n se explican:<\/p>\n<p>Administraciones P\u00fablicas: para el cumplimiento de las obligaciones legales a las que Amigas de la Tierra est\u00e1 sujeta por su actividad.<br \/>\nDestinatarios\/as de peticiones y campa\u00f1as: Cuando se firma una petici\u00f3n o se participa con datos en una acci\u00f3n, el destinatario\/a de la campa\u00f1a recibe de Amigas de la Tierra los datos imprescindibles para cumplir con las obligaciones derivadas de estas campa\u00f1as, que podr\u00e1n ser: nombre, apellidos, DNI, c\u00f3digo postal y correo electr\u00f3nico\u201d. Amigas de la Tierra informar\u00e1 en cada campa\u00f1a los destinatarios\/as de la misma.<br \/>\nProveedores que precisen acceder a datos para la prestaci\u00f3n de servicios que Amigas de la Tierra haya contratado a dichos proveedores, y con los cuales Amigas de la Tierra tiene suscritos los contratos de confidencialidad y de tratamiento de datos personales necesarios y exigidos por la normativa para proteger su privacidad.<br \/>\nAquellas cesiones a terceros que sean necesarias para la organizaci\u00f3n o coordinaci\u00f3n de las campa\u00f1as, actividades e iniciativas en las que voluntariamente participes.<br \/>\nPara tramitar el pago de las cuotas de afiliaci\u00f3n (i.e. entidades bancarias y\/o financieras propietarias de los medios de pago utilizados, pasarelas de pago).<\/p>\n<p>Si en el futuro Amigas de la Tierra realizara otras cesiones de datos personales se informar\u00e1 debidamente.<\/p>\n<p><strong>Plazo de conservaci\u00f3n de datos personales<\/strong><\/p>\n<p>Los datos personales se conservar\u00e1n mientras se mantenga la relaci\u00f3n con Amigas de la Tierra, e incluso tras la finalizaci\u00f3n de dicha relaci\u00f3n por cualquier causa durante los plazos de prescripci\u00f3n legales que sean de aplicaci\u00f3n, si no se comunica lo contrario. En este supuesto, se tratar\u00e1n a efectos de acreditar el cumplimiento de nuestras obligaciones legales y\/o contractuales. Conservaremos informaci\u00f3n personal el tiempo necesario o permitido en atenci\u00f3n a los fines para los cuales se haya obtenido.<\/p>\n<p><strong>\u00a0Datos personas de menores de 18 a\u00f1os<\/strong><\/p>\n<p>No trataremos datos de menores de edad sin previa autorizaci\u00f3n de padres o tutores. Solamente con su acuerdo, podr\u00e1n participar en nuestras campa\u00f1as y actividades en la forma en que en cada caso se indique.<\/p>\n<p><strong>\u00a0Derechos<\/strong><\/p>\n<p>Tienes derecho a obtener confirmaci\u00f3n sobre si en Amigas de la Tierra estamos tratando datos personales que te conciernan, o no.<\/p>\n<p>Asimismo, tienes derecho a acceder a tus datos personales, as\u00ed como a solicitar la rectificaci\u00f3n de los datos inexactos o, en su caso, solicitar su supresi\u00f3n cuando, entre otros motivos, los datos ya no sean necesarios para los fines que fueron recogidos.<\/p>\n<p>En determinadas circunstancias, podr\u00e1s solicitar la limitaci\u00f3n del tratamiento de tus datos, en cuyo caso \u00fanicamente los conservaremos para el ejercicio o la defensa de reclamaciones.<\/p>\n<p>En determinadas circunstancias y por motivos relacionados con tu situaci\u00f3n particular, podr\u00e1s oponerte al tratamiento de tus datos. Amigas de la Tierra dejar\u00e1 de tratar los datos, salvo por motivos leg\u00edtimos imperiosos, o el ejercicio o la defensa de posibles reclamaciones.<\/p>\n<p>Asimismo, puedes ejercer el derecho a la portabilidad de los datos, as\u00ed como retirar los consentimientos facilitados en cualquier momento, sin que ello afecte a la licitud del tratamiento basado en el consentimiento previo a su retirada.<\/p>\n<p>Si deseas ejercer cualquiera de tus derechos puedes dirigirte a nosotros enviando una comunicaci\u00f3n escrita a\u00a0 nuestras oficinas en C\/ Bustos, 2, 28038 Madrid.<\/p>\n<p>La solicitud de ejercicio de cualesquiera de tus derechos deber\u00e1 ir acompa\u00f1ada de una copia de documento oficial que te identifique (DNI o documento acreditativo).<\/p>\n<p><strong>Entorno seguro<\/strong><\/p>\n<p>Esta p\u00e1gina est\u00e1 alojada en un servidor seguro. Toda la informaci\u00f3n personal que nos env\u00edas a trav\u00e9s de los diferentes formularios es tratada por medio de un est\u00e1ndar de seguridad, Secure Sockets Layer (SSL), tecnolog\u00eda que evita la intercepci\u00f3n de esta informaci\u00f3n por parte de terceros.<\/p>\n<p><strong>Pol\u00edtica de Cookies<\/strong><\/p>\n<p>El sitio web tierra.org, titularidad de Amigas de la Tierra Espa\u00f1a, utiliza cookies propias y de terceros para mejorar la experiencia de sus usuarios y usuarias.<\/p>\n<p>Las cookies son archivos que utilizan pr\u00e1cticamente todas las webs. Al navegar por nuestra p\u00e1gina se instalan en tu navegador o dispositivo para asegurar que la web funciona correctamente y almacenar informaci\u00f3n sobre tu visita.<\/p>\n<p>Los datos que nos proporcionan las cookies tratan al usuario de forma an\u00f3nima y en ning\u00fan caso almacenan informaci\u00f3n personal. Nuestro sitio web recoge datos tales como direcciones IP, p\u00e1ginas visitadas y archivos descargados, con el objeto de conocer a nivel general los h\u00e1bitos y preferencias de nuestros usuarios. Esta informaci\u00f3n no nos dice nada acerca de tu identidad y se utiliza \u00fanicamente para mejorar los contenidos y la experiencia de navegaci\u00f3n.<\/p>\n<p>En todo momento podr\u00e1s acceder a la configuraci\u00f3n de tu navegador para modificar o desactivar las cookies, y seguir\u00e1s accediendo a nuestros contenidos. Aunque es posible que la calidad en el funcionamiento de la web se vea afectada sin el uso de las cookies.<\/p>\n<p><strong>\u00a0Enlaces a terceros<\/strong><\/p>\n<p>Nuestro sitio web puede incluir enlaces externos a p\u00e1ginas de otras personas o entidades. En ning\u00fan caso somos responsables de sus contenidos y servicios, que est\u00e1n fuera de nuestro control, ni de los da\u00f1os, directos o indirectos, que puedan ser causados por el uso de estos sitios.<\/p>\n<p>Si tienes cualquier duda o sugerencia puedes ponerte en contacto con nosotros en\u00a0<a href=\"mailto:tierra@tierra.org\">tierra@tierra.org<\/a><\/p>\n<\/div><\/div><\/div><\/div><\/div><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"100-width.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-3","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/alargascencia.org\/es\/wp-json\/wp\/v2\/pages\/3","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alargascencia.org\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/alargascencia.org\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/alargascencia.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/alargascencia.org\/es\/wp-json\/wp\/v2\/comments?post=3"}],"version-history":[{"count":5,"href":"https:\/\/alargascencia.org\/es\/wp-json\/wp\/v2\/pages\/3\/revisions"}],"predecessor-version":[{"id":16728,"href":"https:\/\/alargascencia.org\/es\/wp-json\/wp\/v2\/pages\/3\/revisions\/16728"}],"wp:attachment":[{"href":"https:\/\/alargascencia.org\/es\/wp-json\/wp\/v2\/media?parent=3"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}